{"id":373,"date":"2016-10-19T14:24:37","date_gmt":"2016-10-19T12:24:37","guid":{"rendered":"https:\/\/kermobile.com\/?p=373"},"modified":"2016-10-19T14:24:37","modified_gmt":"2016-10-19T12:24:37","slug":"mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre","status":"publish","type":"post","link":"https:\/\/kermobile.com\/en\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/","title":{"rendered":"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Entre assurances, la concurrence est rude et les compagnies sont pr\u00eates \u00e0 quelques concessions pour recruter de nouveaux clients<strong>. Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances<\/strong>&nbsp;permet d\u2019obtenir la meilleure offre en termes de co\u00fbts et de garanties&nbsp;!<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><strong>Diversifier les sources&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les comparateurs en ligne sont plut\u00f4t au point pour comparer les offres d\u2019assurances immobili\u00e8res. Ils sont organis\u00e9s pour proposer une s\u00e9lection d\u2019offres en provenance d\u2019un certain nombre de compagnies d\u2019assurances. Toutefois, rares sont les comparateurs capable d\u2019interroger l\u2019exhaustivit\u00e9 du march\u00e9, car g\u00e9n\u00e9ralement ils ne comparent que les assureurs faisant partie de leur panel&nbsp;et mettent donc en concurrence un nombre limit\u00e9 de compagnies, pouvant omettre les offres d\u2019autres compagnies plus int\u00e9ressantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De leur c\u00f4t\u00e9, la plupart des assureurs proposent aussi d\u2019\u00e9tablir des devis gratuits en ligne. Les plus courageux pourront ainsi consulter un spectre complet de compagnies d\u2019assurance pour peu que la t\u00e2che de remplir un nombre important de formulaires d\u2019inscription ne rebute pas le client.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Etudier les r\u00e9sultats de plusieurs compagnies diff\u00e9rentes ainsi que les comparateurs en ligne permet d\u2019\u00e9tablir une pr\u00e9s\u00e9lection des assureurs qui proposent les offres les plus attractives. Il sera alors ais\u00e9 de leur demander l\u2019\u00e9dition d\u2019un devis personnalis\u00e9 et ensuite le n\u00e9gocier.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><strong>Faire appel \u00e0 un courtier<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le courtier en assurances agit souvent en ind\u00e9pendant m\u00eame s\u2019il est r\u00e9mun\u00e9r\u00e9 par une ou plusieurs soci\u00e9t\u00e9s d\u2019assurances. Il est donc bien plac\u00e9 pour conseiller les assur\u00e9s et&nbsp;<strong>mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances<\/strong>. Son expertise et son r\u00f4le de conseil le mettent en situation de pouvoir n\u00e9gocier au mieux les int\u00e9r\u00eats de son client.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Devis et comparatifs en main, les propri\u00e9taires ou gestionnaires immobiliers sont arm\u00e9s pour&nbsp;<strong>mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances&nbsp;<\/strong>et obtenir la meilleure offre en les d\u00e9marchant directement.&nbsp; En plus de n\u00e9gocier les tarifs et les garanties, on s\u2019attardera sur les niveaux de franchises propos\u00e9s et sur les exclusions de garanties.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre assurances, la concurrence est rude et les compagnies sont pr\u00eates \u00e0 quelques concessions pour recruter de nouveaux clients. Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances&nbsp;permet d\u2019obtenir la meilleure offre en termes de co\u00fbts et de garanties&nbsp;! Diversifier les sources&nbsp; Les comparateurs en ligne sont plut\u00f4t au point pour comparer les offres d\u2019assurances immobili\u00e8res. Ils sont [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,17],"tags":[13,73,49,74,75],"class_list":["post-373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-francais","tag-assurances","tag-concurrence","tag-prime","tag-societes","tag-tarif"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre - KerMobile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre - KerMobile\" \/>\n<meta property=\"og:description\" content=\"Entre assurances, la concurrence est rude et les compagnies sont pr\u00eates \u00e0 quelques concessions pour recruter de nouveaux clients. Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances&nbsp;permet d\u2019obtenir la meilleure offre en termes de co\u00fbts et de garanties&nbsp;! Diversifier les sources&nbsp; Les comparateurs en ligne sont plut\u00f4t au point pour comparer les offres d\u2019assurances immobili\u00e8res. Ils sont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/\" \/>\n<meta property=\"og:site_name\" content=\"KerMobile\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-19T12:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kermobile.com\/wp-content\/uploads\/2022\/03\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruno de Terline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno de Terline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/\"},\"author\":{\"name\":\"Bruno de Terline\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/#\\\/schema\\\/person\\\/21e214820521217b41a8b9a3ff818da9\"},\"headline\":\"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre\",\"datePublished\":\"2016-10-19T12:24:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/\"},\"wordCount\":386,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kermobile.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg\",\"keywords\":[\"ASSURANCES\",\"CONCURRENCE\",\"PRIME\",\"SOCI\u00c9T\u00c9S\",\"TARIF\"],\"articleSection\":[\"Blog\",\"Fran\u00e7ais\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/\",\"url\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/\",\"name\":\"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre - KerMobile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kermobile.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg\",\"datePublished\":\"2016-10-19T12:24:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/#\\\/schema\\\/person\\\/21e214820521217b41a8b9a3ff818da9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kermobile.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg\",\"contentUrl\":\"https:\\\/\\\/kermobile.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg\",\"width\":850,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/kermobile.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/#website\",\"url\":\"https:\\\/\\\/kermobile.com\\\/\",\"name\":\"KerMobile\",\"description\":\"KerMobile Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kermobile.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kermobile.com\\\/#\\\/schema\\\/person\\\/21e214820521217b41a8b9a3ff818da9\",\"name\":\"Bruno de Terline\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4d8e17951b6e45c3b864d5ec241218ccb0277712c2518ea0e6cd1dc20067bfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4d8e17951b6e45c3b864d5ec241218ccb0277712c2518ea0e6cd1dc20067bfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4d8e17951b6e45c3b864d5ec241218ccb0277712c2518ea0e6cd1dc20067bfa?s=96&d=mm&r=g\",\"caption\":\"Bruno de Terline\"},\"url\":\"https:\\\/\\\/kermobile.com\\\/en\\\/author\\\/bruno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre - KerMobile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/","og_locale":"en_US","og_type":"article","og_title":"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre - KerMobile","og_description":"Entre assurances, la concurrence est rude et les compagnies sont pr\u00eates \u00e0 quelques concessions pour recruter de nouveaux clients. Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances&nbsp;permet d\u2019obtenir la meilleure offre en termes de co\u00fbts et de garanties&nbsp;! Diversifier les sources&nbsp; Les comparateurs en ligne sont plut\u00f4t au point pour comparer les offres d\u2019assurances immobili\u00e8res. Ils sont [&hellip;]","og_url":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/","og_site_name":"KerMobile","article_published_time":"2016-10-19T12:24:37+00:00","og_image":[{"width":850,"height":514,"url":"https:\/\/kermobile.com\/wp-content\/uploads\/2022\/03\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg","type":"image\/jpeg"}],"author":"Bruno de Terline","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bruno de Terline","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#article","isPartOf":{"@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/"},"author":{"name":"Bruno de Terline","@id":"https:\/\/kermobile.com\/#\/schema\/person\/21e214820521217b41a8b9a3ff818da9"},"headline":"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre","datePublished":"2016-10-19T12:24:37+00:00","mainEntityOfPage":{"@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/"},"wordCount":386,"commentCount":0,"image":{"@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#primaryimage"},"thumbnailUrl":"https:\/\/kermobile.com\/wp-content\/uploads\/2022\/03\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg","keywords":["ASSURANCES","CONCURRENCE","PRIME","SOCI\u00c9T\u00c9S","TARIF"],"articleSection":["Blog","Fran\u00e7ais"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/","url":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/","name":"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre - KerMobile","isPartOf":{"@id":"https:\/\/kermobile.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#primaryimage"},"image":{"@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#primaryimage"},"thumbnailUrl":"https:\/\/kermobile.com\/wp-content\/uploads\/2022\/03\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg","datePublished":"2016-10-19T12:24:37+00:00","author":{"@id":"https:\/\/kermobile.com\/#\/schema\/person\/21e214820521217b41a8b9a3ff818da9"},"breadcrumb":{"@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#primaryimage","url":"https:\/\/kermobile.com\/wp-content\/uploads\/2022\/03\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg","contentUrl":"https:\/\/kermobile.com\/wp-content\/uploads\/2022\/03\/K_P2_11_Mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre.jpg","width":850,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/kermobile.com\/mettre-en-concurrence-les-societes-dassurances-pour-obtenir-la-meilleure-offre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kermobile.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Mettre en concurrence les soci\u00e9t\u00e9s d\u2019assurances pour obtenir la meilleure offre"}]},{"@type":"WebSite","@id":"https:\/\/kermobile.com\/#website","url":"https:\/\/kermobile.com\/","name":"KerMobile","description":"KerMobile Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kermobile.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kermobile.com\/#\/schema\/person\/21e214820521217b41a8b9a3ff818da9","name":"Bruno de Terline","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e4d8e17951b6e45c3b864d5ec241218ccb0277712c2518ea0e6cd1dc20067bfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e4d8e17951b6e45c3b864d5ec241218ccb0277712c2518ea0e6cd1dc20067bfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4d8e17951b6e45c3b864d5ec241218ccb0277712c2518ea0e6cd1dc20067bfa?s=96&d=mm&r=g","caption":"Bruno de Terline"},"url":"https:\/\/kermobile.com\/en\/author\/bruno\/"}]}},"_links":{"self":[{"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":0,"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/media\/217"}],"wp:attachment":[{"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kermobile.com\/en\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}